{"id":7955,"date":"2024-05-08T16:49:29","date_gmt":"2024-05-08T16:49:29","guid":{"rendered":"http:\/\/www.colefillesbalears.com\/web\/?p=7955"},"modified":"2024-05-08T17:03:22","modified_gmt":"2024-05-08T17:03:22","slug":"32e-aniversari-del-colef-illes-baleares","status":"publish","type":"post","link":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/","title":{"rendered":"32\u00e8 aniversari del COLEF Illes Baleares"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El dia 8 de maig de 2024 es celebren 32 anys del COLEF Illes Balears. <\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">El 8 de maig de 1992 es va crear el COLEF Illes Balears Reial decret 478\/1992, de 8 de maig, sobre constituci\u00f3, per segregaci\u00f3, del Col\u00b7legi Oficial de Professors i Llicenciats en Educaci\u00f3 F\u00edsica d&#8217;illes Balears.<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeqSkkH_BViP--No5FJ0r3VAT2rgeMEIcp4D87D2aSVOEBauw\/viewform\"><img decoding=\"async\" loading=\"lazy\" width=\"1447\" height=\"2048\" src=\"http:\/\/www.colefillesbalears.com\/web\/wp-content\/uploads\/2024\/05\/32aniversari.jpeg\" alt=\"\" class=\"wp-image-7956\" srcset=\"https:\/\/www.colefillesbalears.com\/web\/wp-content\/uploads\/2024\/05\/32aniversari.jpeg 1447w, https:\/\/www.colefillesbalears.com\/web\/wp-content\/uploads\/2024\/05\/32aniversari-768x1086.jpeg 768w\" sizes=\"(max-width: 1447px) 100vw, 1447px\" \/><\/a><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Col\u00b7legiats\/es, per a celebrar el nostre 32 aniversari, el Colef Illes Balears, juntament amb la Federaci\u00f3 Balear de Golf us convida a:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Cl\u00ednics iniciaci\u00f3 al golf i refrigeri <\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Divendres 31\/05\/2024<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">De 18 a 21.00 hores<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Llocs:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">&#8211; Golf S\u00f3n Quint (Mallorca)<br>&#8211; Golf Eivissa (Eivissa)<br>&#8211; Golf S\u00f3n Parc (Menorca)<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Hi ha places limitades!!! <\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeqSkkH_BViP--No5FJ0r3VAT2rgeMEIcp4D87D2aSVOEBauw\/viewform\" target=\"_blank\" rel=\"noreferrer noopener\">Inscripcions<\/a><\/h2>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dia 8 de maig de 2024 es celebren 32 anys del COLEF Illes Balears. El 8 de maig de 1992 es va crear el COLEF Illes Balears Reial decret 478\/1992, de 8 de maig, sobre constituci\u00f3, per segregaci\u00f3, del Col\u00b7legi Oficial de Professors i Llicenciats en Educaci\u00f3 F\u00edsica d&#8217;illes Balears. Col\u00b7legiats\/es, per a celebrar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[498],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>32\u00e8 aniversari del COLEF Illes Baleares - COLEF Illes Balears<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"32\u00e8 aniversari del COLEF Illes Baleares - COLEF Illes Balears\" \/>\n<meta property=\"og:description\" content=\"El dia 8 de maig de 2024 es celebren 32 anys del COLEF Illes Balears. El 8 de maig de 1992 es va crear el COLEF Illes Balears Reial decret 478\/1992, de 8 de maig, sobre constituci\u00f3, per segregaci\u00f3, del Col\u00b7legi Oficial de Professors i Llicenciats en Educaci\u00f3 F\u00edsica d&#8217;illes Balears. Col\u00b7legiats\/es, per a celebrar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/\" \/>\n<meta property=\"og:site_name\" content=\"COLEF Illes Balears\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/colef.illesbalears\/?ref=bookmarks\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/colef.illesbalears\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-08T16:49:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T17:03:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.colefillesbalears.com\/web\/wp-content\/uploads\/2024\/05\/32aniversari.jpeg\" \/>\n<meta name=\"author\" content=\"RAUL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@COLEFBalears\" \/>\n<meta name=\"twitter:site\" content=\"@COLEFBalears\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"RAUL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/\"},\"author\":{\"name\":\"RAUL\",\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/#\/schema\/person\/67bfa54d8a7a8533be8dac16e810fde7\"},\"headline\":\"32\u00e8 aniversari del COLEF Illes Baleares\",\"datePublished\":\"2024-05-08T16:49:29+00:00\",\"dateModified\":\"2024-05-08T17:03:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/\"},\"wordCount\":107,\"publisher\":{\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/#organization\"},\"articleSection\":[\"Actualitat\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/\",\"url\":\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/\",\"name\":\"32\u00e8 aniversari del COLEF Illes Baleares - COLEF Illes Balears\",\"isPartOf\":{\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/#website\"},\"datePublished\":\"2024-05-08T16:49:29+00:00\",\"dateModified\":\"2024-05-08T17:03:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.colefillesbalears.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"32\u00e8 aniversari del COLEF Illes Baleares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/#website\",\"url\":\"https:\/\/www.colefillesbalears.com\/web\/\",\"name\":\"COLEF Illes Balears\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colefillesbalears.com\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/#organization\",\"name\":\"Col\u00b7legi Oficial de Llicenciats en Ci\u00e8ncies de l'Activitat F\u00edsica i l'Esport de les Illes Balears\",\"url\":\"https:\/\/www.colefillesbalears.com\/web\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UClDRzEzUh03bePGcdVFw1cQ\/featured\",\"https:\/\/www.facebook.com\/colef.illesbalears\/?ref=bookmarks\",\"https:\/\/twitter.com\/COLEFBalears\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.colefillesbalears.com\/web\/wp-content\/uploads\/2019\/05\/logo-colef-5.png\",\"contentUrl\":\"http:\/\/www.colefillesbalears.com\/web\/wp-content\/uploads\/2019\/05\/logo-colef-5.png\",\"width\":414,\"height\":175,\"caption\":\"Col\u00b7legi Oficial de Llicenciats en Ci\u00e8ncies de l'Activitat F\u00edsica i l'Esport de les Illes Balears\"},\"image\":{\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.colefillesbalears.com\/web\/#\/schema\/person\/67bfa54d8a7a8533be8dac16e810fde7\",\"name\":\"RAUL\",\"sameAs\":[\"https:\/\/www.facebook.com\/colef.illesbalears\/\",\"https:\/\/twitter.com\/COLEFBalears\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"32\u00e8 aniversari del COLEF Illes Baleares - COLEF Illes Balears","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/","og_locale":"es_ES","og_type":"article","og_title":"32\u00e8 aniversari del COLEF Illes Baleares - COLEF Illes Balears","og_description":"El dia 8 de maig de 2024 es celebren 32 anys del COLEF Illes Balears. El 8 de maig de 1992 es va crear el COLEF Illes Balears Reial decret 478\/1992, de 8 de maig, sobre constituci\u00f3, per segregaci\u00f3, del Col\u00b7legi Oficial de Professors i Llicenciats en Educaci\u00f3 F\u00edsica d&#8217;illes Balears. Col\u00b7legiats\/es, per a celebrar [&hellip;]","og_url":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/","og_site_name":"COLEF Illes Balears","article_publisher":"https:\/\/www.facebook.com\/colef.illesbalears\/?ref=bookmarks","article_author":"https:\/\/www.facebook.com\/colef.illesbalears\/","article_published_time":"2024-05-08T16:49:29+00:00","article_modified_time":"2024-05-08T17:03:22+00:00","og_image":[{"url":"http:\/\/www.colefillesbalears.com\/web\/wp-content\/uploads\/2024\/05\/32aniversari.jpeg"}],"author":"RAUL","twitter_card":"summary_large_image","twitter_creator":"@COLEFBalears","twitter_site":"@COLEFBalears","twitter_misc":{"Escrito por":"RAUL","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/#article","isPartOf":{"@id":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/"},"author":{"name":"RAUL","@id":"https:\/\/www.colefillesbalears.com\/web\/#\/schema\/person\/67bfa54d8a7a8533be8dac16e810fde7"},"headline":"32\u00e8 aniversari del COLEF Illes Baleares","datePublished":"2024-05-08T16:49:29+00:00","dateModified":"2024-05-08T17:03:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/"},"wordCount":107,"publisher":{"@id":"https:\/\/www.colefillesbalears.com\/web\/#organization"},"articleSection":["Actualitat"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/","url":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/","name":"32\u00e8 aniversari del COLEF Illes Baleares - COLEF Illes Balears","isPartOf":{"@id":"https:\/\/www.colefillesbalears.com\/web\/#website"},"datePublished":"2024-05-08T16:49:29+00:00","dateModified":"2024-05-08T17:03:22+00:00","breadcrumb":{"@id":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.colefillesbalears.com\/web\/2024\/05\/08\/32e-aniversari-del-colef-illes-baleares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.colefillesbalears.com\/web\/"},{"@type":"ListItem","position":2,"name":"32\u00e8 aniversari del COLEF Illes Baleares"}]},{"@type":"WebSite","@id":"https:\/\/www.colefillesbalears.com\/web\/#website","url":"https:\/\/www.colefillesbalears.com\/web\/","name":"COLEF Illes Balears","description":"","publisher":{"@id":"https:\/\/www.colefillesbalears.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colefillesbalears.com\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.colefillesbalears.com\/web\/#organization","name":"Col\u00b7legi Oficial de Llicenciats en Ci\u00e8ncies de l'Activitat F\u00edsica i l'Esport de les Illes Balears","url":"https:\/\/www.colefillesbalears.com\/web\/","sameAs":["https:\/\/www.youtube.com\/channel\/UClDRzEzUh03bePGcdVFw1cQ\/featured","https:\/\/www.facebook.com\/colef.illesbalears\/?ref=bookmarks","https:\/\/twitter.com\/COLEFBalears"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.colefillesbalears.com\/web\/#\/schema\/logo\/image\/","url":"http:\/\/www.colefillesbalears.com\/web\/wp-content\/uploads\/2019\/05\/logo-colef-5.png","contentUrl":"http:\/\/www.colefillesbalears.com\/web\/wp-content\/uploads\/2019\/05\/logo-colef-5.png","width":414,"height":175,"caption":"Col\u00b7legi Oficial de Llicenciats en Ci\u00e8ncies de l'Activitat F\u00edsica i l'Esport de les Illes Balears"},"image":{"@id":"https:\/\/www.colefillesbalears.com\/web\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.colefillesbalears.com\/web\/#\/schema\/person\/67bfa54d8a7a8533be8dac16e810fde7","name":"RAUL","sameAs":["https:\/\/www.facebook.com\/colef.illesbalears\/","https:\/\/twitter.com\/COLEFBalears"]}]}},"_links":{"self":[{"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/posts\/7955"}],"collection":[{"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/comments?post=7955"}],"version-history":[{"count":2,"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/posts\/7955\/revisions"}],"predecessor-version":[{"id":7958,"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/posts\/7955\/revisions\/7958"}],"wp:attachment":[{"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/media?parent=7955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/categories?post=7955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colefillesbalears.com\/web\/wp-json\/wp\/v2\/tags?post=7955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}